{"id":1009,"date":"2022-12-12T16:33:42","date_gmt":"2022-12-12T21:33:42","guid":{"rendered":"https:\/\/lesfringales.com\/product\/vegetarian-poutine\/"},"modified":"2023-01-20T14:25:06","modified_gmt":"2023-01-20T19:25:06","slug":"poutine-vegetarienne","status":"publish","type":"product","link":"https:\/\/lesfringales.com\/fr\/produit\/poutine-vegetarienne\/","title":{"rendered":"Poutine V\u00e9g\u00e9tarienne"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Pommes de terre rissol\u00e9es ou frites, fromage en grains, poivrons,oignons, tomates, champignons, sauce brune ou Hollandaise.<\/p>\n","protected":false},"featured_media":747,"comment_status":"open","ping_status":"closed","template":"","meta":{"nf_dc_page":""},"product_brand":[],"product_cat":[57],"product_tag":[95,104,109],"class_list":["post-1009","product","type-product","status-publish","has-post-thumbnail","product_cat-poutines-dejeuner","product_tag-fromage","product_tag-legumes","product_tag-vegetarien","first","instock","featured","taxable","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Poutine V\u00e9g\u00e9tarienne | Les Fringales - D\u00e9jeuner.D\u00eener<\/title>\n<meta name=\"description\" content=\"Pommes de terre rissol\u00e9es ou frites, fromage en grains, poivrons,oignons, tomates, champignons, sauce brune ou Hollandaise.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lesfringales.com\/fr\/produit\/poutine-vegetarienne\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Poutine V\u00e9g\u00e9tarienne | Les Fringales - D\u00e9jeuner.D\u00eener\" \/>\n<meta property=\"og:description\" content=\"Pommes de terre rissol\u00e9es ou frites, fromage en grains, poivrons,oignons, tomates, champignons, sauce brune ou Hollandaise.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lesfringales.com\/fr\/produit\/poutine-vegetarienne\/\" \/>\n<meta property=\"og:site_name\" content=\"Les Fringales - D\u00e9jeuner.D\u00eener\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/restolesfringales\" \/>\n<meta property=\"article:modified_time\" content=\"2023-01-20T19:25:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lesfringales.com\/wp-content\/uploads\/2023\/01\/poutine.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lesfringales.com\\\/fr\\\/produit\\\/poutine-vegetarienne\\\/\",\"url\":\"https:\\\/\\\/lesfringales.com\\\/fr\\\/produit\\\/poutine-vegetarienne\\\/\",\"name\":\"Poutine V\u00e9g\u00e9tarienne | Les Fringales - D\u00e9jeuner.D\u00eener\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lesfringales.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lesfringales.com\\\/fr\\\/produit\\\/poutine-vegetarienne\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lesfringales.com\\\/fr\\\/produit\\\/poutine-vegetarienne\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lesfringales.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/poutine.jpg\",\"datePublished\":\"2022-12-12T21:33:42+00:00\",\"dateModified\":\"2023-01-20T19:25:06+00:00\",\"description\":\"Pommes de terre rissol\u00e9es ou frites, fromage en grains, poivrons,oignons, tomates, champignons, sauce brune ou Hollandaise.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lesfringales.com\\\/fr\\\/produit\\\/poutine-vegetarienne\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lesfringales.com\\\/fr\\\/produit\\\/poutine-vegetarienne\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lesfringales.com\\\/fr\\\/produit\\\/poutine-vegetarienne\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lesfringales.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/poutine.jpg\",\"contentUrl\":\"https:\\\/\\\/lesfringales.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/poutine.jpg\",\"width\":1200,\"height\":1200,\"caption\":\"Poutines D\u00e9jeuner\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lesfringales.com\\\/fr\\\/produit\\\/poutine-vegetarienne\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/lesfringales.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Menu\",\"item\":\"https:\\\/\\\/lesfringales.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Poutine V\u00e9g\u00e9tarienne\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lesfringales.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/lesfringales.com\\\/fr\\\/\",\"name\":\"Les Fringales - D\u00e9jeuner.D\u00eener\",\"description\":\"I\u2019ll Take A Coffee With My Sunshine....\",\"publisher\":{\"@id\":\"https:\\\/\\\/lesfringales.com\\\/fr\\\/#organization\"},\"alternateName\":\"Les Fringals\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lesfringales.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lesfringales.com\\\/fr\\\/#organization\",\"name\":\"Les Fringales - D\u00e9jeuner.D\u00eener\",\"alternateName\":\"Les Fringals\",\"url\":\"https:\\\/\\\/lesfringales.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lesfringales.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lesfringales.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/lesfringales.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/logo.png\",\"width\":316,\"height\":152,\"caption\":\"Les Fringales - D\u00e9jeuner.D\u00eener\"},\"image\":{\"@id\":\"https:\\\/\\\/lesfringales.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/restolesfringales\",\"https:\\\/\\\/www.instagram.com\\\/lesfringales_dejeuner.diner\\\/\",\"https:\\\/\\\/www.google.com\\\/search?q=lesfringaleslaval&amp;amp;client=firefox-b-d&amp;amp;ei=mVDMY7mgA7quptQPh9eVuA0&amp;amp;oq=les fringales&amp;amp;gs_lcp=Cgxnd3Mtd2l6LXNlcnAQARgAMgUIABCABDIGCAAQFhAeMgYIABAWEB4yBggAEBYQHjIGCAAQFhAeMgYIABAWEB4yCAgAEBYQHhAPMggIABAWEB4QDzIGCAAQFhAeMgYIABAWEB46CggAEEcQ1gQQsANKBAhBGABKBAhGGABQhQFYhQFg4gpoAXABeACAAU-IAU-SAQExmAEAoAEByAEIwAEB&amp;amp;sclient=gws-wiz-serp&amp;amp;tbs=lf:1,lf_ui:9&amp;amp;tbm=lcl&amp;amp;rflfq=1&amp;amp;num=10&amp;amp;rldimm=4391824261453218602&amp;amp;lqi=ChNsZXMgZnJpbmdhbGVzIGxhdmFsSPL_oc6yuICACFojEAAQARgAGAEYAiITbGVzIGZyaW5nYWxlcyBsYXZhbDICZnKSARRicmVha2Zhc3RfcmVzdGF1cmFudKoBNRABGh4QASIasU6ni1Oc0k-e-ecmICVLJ4TRK76HszS1FrgqESINbGVzIGZyaW5nYWxlcygE&amp;amp;phdesc=T7NFWvuH8XI&amp;amp;ved=2ahUKEwj1jYTYxdn8AhX2jYkEHXAoD9IQvS56BAgNEAE&amp;amp;sa=X&amp;amp;rlst=f#rlfi=hd:;si:4391824261453218602,l,ChNsZXMgZnJpbmdhbGVzIGxhdmFsSPL_oc6yuICACFojEAAQARgAGAEYAiITbGVzIGZyaW5nYWxlcyBsYXZhbDICZnKSARRicmVha2Zhc3RfcmVzdGF1cmFudKoBNRABGh4QASIasU6ni1Oc0k-e-ecmICVLJ4TRK76HszS1FrgqESINbGVzIGZyaW5nYWxlcygE,y,T7NFWvuH8XI;mv:[[45.620182199999995,-73.65968649999999],[45.530364299999995,-73.8163678]];tbs:lrf:!1m4!1u3!2m2!3m1!1e1!1m4!1u2!2m2!2m1!1e1!1m4!1u1!2m2!1m1!1e1!1m4!1u1!2m2!1m1!1e2!2m1!1e2!2m1!1e1!2m1!1e3!3sIAE,lf:1,lf_ui:9\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Poutine V\u00e9g\u00e9tarienne | Les Fringales - D\u00e9jeuner.D\u00eener","description":"Pommes de terre rissol\u00e9es ou frites, fromage en grains, poivrons,oignons, tomates, champignons, sauce brune ou Hollandaise.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lesfringales.com\/fr\/produit\/poutine-vegetarienne\/","og_locale":"fr_FR","og_type":"article","og_title":"Poutine V\u00e9g\u00e9tarienne | Les Fringales - D\u00e9jeuner.D\u00eener","og_description":"Pommes de terre rissol\u00e9es ou frites, fromage en grains, poivrons,oignons, tomates, champignons, sauce brune ou Hollandaise.","og_url":"https:\/\/lesfringales.com\/fr\/produit\/poutine-vegetarienne\/","og_site_name":"Les Fringales - D\u00e9jeuner.D\u00eener","article_publisher":"https:\/\/www.facebook.com\/restolesfringales","article_modified_time":"2023-01-20T19:25:06+00:00","og_image":[{"width":1200,"height":1200,"url":"https:\/\/lesfringales.com\/wp-content\/uploads\/2023\/01\/poutine.jpg","type":"image\/jpeg"}],"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/lesfringales.com\/fr\/produit\/poutine-vegetarienne\/","url":"https:\/\/lesfringales.com\/fr\/produit\/poutine-vegetarienne\/","name":"Poutine V\u00e9g\u00e9tarienne | Les Fringales - D\u00e9jeuner.D\u00eener","isPartOf":{"@id":"https:\/\/lesfringales.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lesfringales.com\/fr\/produit\/poutine-vegetarienne\/#primaryimage"},"image":{"@id":"https:\/\/lesfringales.com\/fr\/produit\/poutine-vegetarienne\/#primaryimage"},"thumbnailUrl":"https:\/\/lesfringales.com\/wp-content\/uploads\/2023\/01\/poutine.jpg","datePublished":"2022-12-12T21:33:42+00:00","dateModified":"2023-01-20T19:25:06+00:00","description":"Pommes de terre rissol\u00e9es ou frites, fromage en grains, poivrons,oignons, tomates, champignons, sauce brune ou Hollandaise.","breadcrumb":{"@id":"https:\/\/lesfringales.com\/fr\/produit\/poutine-vegetarienne\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lesfringales.com\/fr\/produit\/poutine-vegetarienne\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lesfringales.com\/fr\/produit\/poutine-vegetarienne\/#primaryimage","url":"https:\/\/lesfringales.com\/wp-content\/uploads\/2023\/01\/poutine.jpg","contentUrl":"https:\/\/lesfringales.com\/wp-content\/uploads\/2023\/01\/poutine.jpg","width":1200,"height":1200,"caption":"Poutines D\u00e9jeuner"},{"@type":"BreadcrumbList","@id":"https:\/\/lesfringales.com\/fr\/produit\/poutine-vegetarienne\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/lesfringales.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Menu","item":"https:\/\/lesfringales.com\/fr\/"},{"@type":"ListItem","position":3,"name":"Poutine V\u00e9g\u00e9tarienne"}]},{"@type":"WebSite","@id":"https:\/\/lesfringales.com\/fr\/#website","url":"https:\/\/lesfringales.com\/fr\/","name":"Les Fringales - D\u00e9jeuner.D\u00eener","description":"I\u2019ll Take A Coffee With My Sunshine....","publisher":{"@id":"https:\/\/lesfringales.com\/fr\/#organization"},"alternateName":"Les Fringals","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lesfringales.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/lesfringales.com\/fr\/#organization","name":"Les Fringales - D\u00e9jeuner.D\u00eener","alternateName":"Les Fringals","url":"https:\/\/lesfringales.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lesfringales.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/lesfringales.com\/wp-content\/uploads\/2022\/12\/logo.png","contentUrl":"https:\/\/lesfringales.com\/wp-content\/uploads\/2022\/12\/logo.png","width":316,"height":152,"caption":"Les Fringales - D\u00e9jeuner.D\u00eener"},"image":{"@id":"https:\/\/lesfringales.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/restolesfringales","https:\/\/www.instagram.com\/lesfringales_dejeuner.diner\/","https:\/\/www.google.com\/search?q=lesfringaleslaval&amp;amp;client=firefox-b-d&amp;amp;ei=mVDMY7mgA7quptQPh9eVuA0&amp;amp;oq=les fringales&amp;amp;gs_lcp=Cgxnd3Mtd2l6LXNlcnAQARgAMgUIABCABDIGCAAQFhAeMgYIABAWEB4yBggAEBYQHjIGCAAQFhAeMgYIABAWEB4yCAgAEBYQHhAPMggIABAWEB4QDzIGCAAQFhAeMgYIABAWEB46CggAEEcQ1gQQsANKBAhBGABKBAhGGABQhQFYhQFg4gpoAXABeACAAU-IAU-SAQExmAEAoAEByAEIwAEB&amp;amp;sclient=gws-wiz-serp&amp;amp;tbs=lf:1,lf_ui:9&amp;amp;tbm=lcl&amp;amp;rflfq=1&amp;amp;num=10&amp;amp;rldimm=4391824261453218602&amp;amp;lqi=ChNsZXMgZnJpbmdhbGVzIGxhdmFsSPL_oc6yuICACFojEAAQARgAGAEYAiITbGVzIGZyaW5nYWxlcyBsYXZhbDICZnKSARRicmVha2Zhc3RfcmVzdGF1cmFudKoBNRABGh4QASIasU6ni1Oc0k-e-ecmICVLJ4TRK76HszS1FrgqESINbGVzIGZyaW5nYWxlcygE&amp;amp;phdesc=T7NFWvuH8XI&amp;amp;ved=2ahUKEwj1jYTYxdn8AhX2jYkEHXAoD9IQvS56BAgNEAE&amp;amp;sa=X&amp;amp;rlst=f#rlfi=hd:;si:4391824261453218602,l,ChNsZXMgZnJpbmdhbGVzIGxhdmFsSPL_oc6yuICACFojEAAQARgAGAEYAiITbGVzIGZyaW5nYWxlcyBsYXZhbDICZnKSARRicmVha2Zhc3RfcmVzdGF1cmFudKoBNRABGh4QASIasU6ni1Oc0k-e-ecmICVLJ4TRK76HszS1FrgqESINbGVzIGZyaW5nYWxlcygE,y,T7NFWvuH8XI;mv:[[45.620182199999995,-73.65968649999999],[45.530364299999995,-73.8163678]];tbs:lrf:!1m4!1u3!2m2!3m1!1e1!1m4!1u2!2m2!2m1!1e1!1m4!1u1!2m2!1m1!1e1!1m4!1u1!2m2!1m1!1e2!2m1!1e2!2m1!1e1!2m1!1e3!3sIAE,lf:1,lf_ui:9"]}]}},"_links":{"self":[{"href":"https:\/\/lesfringales.com\/fr\/wp-json\/wp\/v2\/product\/1009","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lesfringales.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/lesfringales.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/lesfringales.com\/fr\/wp-json\/wp\/v2\/comments?post=1009"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lesfringales.com\/fr\/wp-json\/wp\/v2\/media\/747"}],"wp:attachment":[{"href":"https:\/\/lesfringales.com\/fr\/wp-json\/wp\/v2\/media?parent=1009"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/lesfringales.com\/fr\/wp-json\/wp\/v2\/product_brand?post=1009"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/lesfringales.com\/fr\/wp-json\/wp\/v2\/product_cat?post=1009"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/lesfringales.com\/fr\/wp-json\/wp\/v2\/product_tag?post=1009"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}