{"id":54,"count":8,"description":"","link":"https:\/\/lesfringales.com\/fr\/categorie-produit\/crepes-sucrees\/","name":"Cr\u00eapes Sucr\u00e9es","slug":"crepes-sucrees","taxonomy":"product_cat","parent":0,"meta":[],"menu_order":3,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cr\u00eapes Sucr\u00e9es | Les Fringales - D\u00e9jeuner.D\u00eener<\/title>\n<meta name=\"description\" content=\"Chez soi, on les cuisine pour faire plaisir \u00e0 ceux qu\u2019on aime. Chez nous, on les pr\u00e9pare avec amour pour que vous puissiez les savourer avec ceux que vous aimez!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lesfringales.com\/fr\/categorie-produit\/crepes-sucrees\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cr\u00eapes Sucr\u00e9es | Les Fringales - D\u00e9jeuner.D\u00eener\" \/>\n<meta property=\"og:description\" content=\"Chez soi, on les cuisine pour faire plaisir \u00e0 ceux qu\u2019on aime. Chez nous, on les pr\u00e9pare avec amour pour que vous puissiez les savourer avec ceux que vous aimez!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lesfringales.com\/fr\/categorie-produit\/crepes-sucrees\/\" \/>\n<meta property=\"og:site_name\" content=\"Les Fringales - D\u00e9jeuner.D\u00eener\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lesfringales.com\/wp-content\/uploads\/2022\/12\/logo.png\" \/>\n\t<meta property=\"og:image:width\" content=\"316\" \/>\n\t<meta property=\"og:image:height\" content=\"152\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/lesfringales.com\\\/fr\\\/categorie-produit\\\/crepes-sucrees\\\/\",\"url\":\"https:\\\/\\\/lesfringales.com\\\/fr\\\/categorie-produit\\\/crepes-sucrees\\\/\",\"name\":\"Cr\u00eapes Sucr\u00e9es | Les Fringales - D\u00e9jeuner.D\u00eener\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lesfringales.com\\\/fr\\\/#website\"},\"description\":\"Chez soi, on les cuisine pour faire plaisir \u00e0 ceux qu\u2019on aime. Chez nous, on les pr\u00e9pare avec amour pour que vous puissiez les savourer avec ceux que vous aimez!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lesfringales.com\\\/fr\\\/categorie-produit\\\/crepes-sucrees\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lesfringales.com\\\/fr\\\/categorie-produit\\\/crepes-sucrees\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/lesfringales.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cr\u00eapes Sucr\u00e9es\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lesfringales.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/lesfringales.com\\\/fr\\\/\",\"name\":\"Les Fringales - D\u00e9jeuner.D\u00eener\",\"description\":\"I\u2019ll Take A Coffee With My Sunshine....\",\"publisher\":{\"@id\":\"https:\\\/\\\/lesfringales.com\\\/fr\\\/#organization\"},\"alternateName\":\"Les Fringals\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lesfringales.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lesfringales.com\\\/fr\\\/#organization\",\"name\":\"Les Fringales - D\u00e9jeuner.D\u00eener\",\"alternateName\":\"Les Fringals\",\"url\":\"https:\\\/\\\/lesfringales.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lesfringales.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lesfringales.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/lesfringales.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/logo.png\",\"width\":316,\"height\":152,\"caption\":\"Les Fringales - D\u00e9jeuner.D\u00eener\"},\"image\":{\"@id\":\"https:\\\/\\\/lesfringales.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/restolesfringales\",\"https:\\\/\\\/www.instagram.com\\\/lesfringales_dejeuner.diner\\\/\",\"https:\\\/\\\/www.google.com\\\/search?q=lesfringaleslaval&amp;amp;client=firefox-b-d&amp;amp;ei=mVDMY7mgA7quptQPh9eVuA0&amp;amp;oq=les fringales&amp;amp;gs_lcp=Cgxnd3Mtd2l6LXNlcnAQARgAMgUIABCABDIGCAAQFhAeMgYIABAWEB4yBggAEBYQHjIGCAAQFhAeMgYIABAWEB4yCAgAEBYQHhAPMggIABAWEB4QDzIGCAAQFhAeMgYIABAWEB46CggAEEcQ1gQQsANKBAhBGABKBAhGGABQhQFYhQFg4gpoAXABeACAAU-IAU-SAQExmAEAoAEByAEIwAEB&amp;amp;sclient=gws-wiz-serp&amp;amp;tbs=lf:1,lf_ui:9&amp;amp;tbm=lcl&amp;amp;rflfq=1&amp;amp;num=10&amp;amp;rldimm=4391824261453218602&amp;amp;lqi=ChNsZXMgZnJpbmdhbGVzIGxhdmFsSPL_oc6yuICACFojEAAQARgAGAEYAiITbGVzIGZyaW5nYWxlcyBsYXZhbDICZnKSARRicmVha2Zhc3RfcmVzdGF1cmFudKoBNRABGh4QASIasU6ni1Oc0k-e-ecmICVLJ4TRK76HszS1FrgqESINbGVzIGZyaW5nYWxlcygE&amp;amp;phdesc=T7NFWvuH8XI&amp;amp;ved=2ahUKEwj1jYTYxdn8AhX2jYkEHXAoD9IQvS56BAgNEAE&amp;amp;sa=X&amp;amp;rlst=f#rlfi=hd:;si:4391824261453218602,l,ChNsZXMgZnJpbmdhbGVzIGxhdmFsSPL_oc6yuICACFojEAAQARgAGAEYAiITbGVzIGZyaW5nYWxlcyBsYXZhbDICZnKSARRicmVha2Zhc3RfcmVzdGF1cmFudKoBNRABGh4QASIasU6ni1Oc0k-e-ecmICVLJ4TRK76HszS1FrgqESINbGVzIGZyaW5nYWxlcygE,y,T7NFWvuH8XI;mv:[[45.620182199999995,-73.65968649999999],[45.530364299999995,-73.8163678]];tbs:lrf:!1m4!1u3!2m2!3m1!1e1!1m4!1u2!2m2!2m1!1e1!1m4!1u1!2m2!1m1!1e1!1m4!1u1!2m2!1m1!1e2!2m1!1e2!2m1!1e1!2m1!1e3!3sIAE,lf:1,lf_ui:9\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cr\u00eapes Sucr\u00e9es | Les Fringales - D\u00e9jeuner.D\u00eener","description":"Chez soi, on les cuisine pour faire plaisir \u00e0 ceux qu\u2019on aime. Chez nous, on les pr\u00e9pare avec amour pour que vous puissiez les savourer avec ceux que vous aimez!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lesfringales.com\/fr\/categorie-produit\/crepes-sucrees\/","og_locale":"fr_FR","og_type":"article","og_title":"Cr\u00eapes Sucr\u00e9es | Les Fringales - D\u00e9jeuner.D\u00eener","og_description":"Chez soi, on les cuisine pour faire plaisir \u00e0 ceux qu\u2019on aime. Chez nous, on les pr\u00e9pare avec amour pour que vous puissiez les savourer avec ceux que vous aimez!","og_url":"https:\/\/lesfringales.com\/fr\/categorie-produit\/crepes-sucrees\/","og_site_name":"Les Fringales - D\u00e9jeuner.D\u00eener","og_image":[{"width":316,"height":152,"url":"https:\/\/lesfringales.com\/wp-content\/uploads\/2022\/12\/logo.png","type":"image\/png"}],"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/lesfringales.com\/fr\/categorie-produit\/crepes-sucrees\/","url":"https:\/\/lesfringales.com\/fr\/categorie-produit\/crepes-sucrees\/","name":"Cr\u00eapes Sucr\u00e9es | Les Fringales - D\u00e9jeuner.D\u00eener","isPartOf":{"@id":"https:\/\/lesfringales.com\/fr\/#website"},"description":"Chez soi, on les cuisine pour faire plaisir \u00e0 ceux qu\u2019on aime. Chez nous, on les pr\u00e9pare avec amour pour que vous puissiez les savourer avec ceux que vous aimez!","breadcrumb":{"@id":"https:\/\/lesfringales.com\/fr\/categorie-produit\/crepes-sucrees\/#breadcrumb"},"inLanguage":"fr-FR"},{"@type":"BreadcrumbList","@id":"https:\/\/lesfringales.com\/fr\/categorie-produit\/crepes-sucrees\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/lesfringales.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Cr\u00eapes Sucr\u00e9es"}]},{"@type":"WebSite","@id":"https:\/\/lesfringales.com\/fr\/#website","url":"https:\/\/lesfringales.com\/fr\/","name":"Les Fringales - D\u00e9jeuner.D\u00eener","description":"I\u2019ll Take A Coffee With My Sunshine....","publisher":{"@id":"https:\/\/lesfringales.com\/fr\/#organization"},"alternateName":"Les Fringals","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lesfringales.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/lesfringales.com\/fr\/#organization","name":"Les Fringales - D\u00e9jeuner.D\u00eener","alternateName":"Les Fringals","url":"https:\/\/lesfringales.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lesfringales.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/lesfringales.com\/wp-content\/uploads\/2022\/12\/logo.png","contentUrl":"https:\/\/lesfringales.com\/wp-content\/uploads\/2022\/12\/logo.png","width":316,"height":152,"caption":"Les Fringales - D\u00e9jeuner.D\u00eener"},"image":{"@id":"https:\/\/lesfringales.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/restolesfringales","https:\/\/www.instagram.com\/lesfringales_dejeuner.diner\/","https:\/\/www.google.com\/search?q=lesfringaleslaval&amp;amp;client=firefox-b-d&amp;amp;ei=mVDMY7mgA7quptQPh9eVuA0&amp;amp;oq=les fringales&amp;amp;gs_lcp=Cgxnd3Mtd2l6LXNlcnAQARgAMgUIABCABDIGCAAQFhAeMgYIABAWEB4yBggAEBYQHjIGCAAQFhAeMgYIABAWEB4yCAgAEBYQHhAPMggIABAWEB4QDzIGCAAQFhAeMgYIABAWEB46CggAEEcQ1gQQsANKBAhBGABKBAhGGABQhQFYhQFg4gpoAXABeACAAU-IAU-SAQExmAEAoAEByAEIwAEB&amp;amp;sclient=gws-wiz-serp&amp;amp;tbs=lf:1,lf_ui:9&amp;amp;tbm=lcl&amp;amp;rflfq=1&amp;amp;num=10&amp;amp;rldimm=4391824261453218602&amp;amp;lqi=ChNsZXMgZnJpbmdhbGVzIGxhdmFsSPL_oc6yuICACFojEAAQARgAGAEYAiITbGVzIGZyaW5nYWxlcyBsYXZhbDICZnKSARRicmVha2Zhc3RfcmVzdGF1cmFudKoBNRABGh4QASIasU6ni1Oc0k-e-ecmICVLJ4TRK76HszS1FrgqESINbGVzIGZyaW5nYWxlcygE&amp;amp;phdesc=T7NFWvuH8XI&amp;amp;ved=2ahUKEwj1jYTYxdn8AhX2jYkEHXAoD9IQvS56BAgNEAE&amp;amp;sa=X&amp;amp;rlst=f#rlfi=hd:;si:4391824261453218602,l,ChNsZXMgZnJpbmdhbGVzIGxhdmFsSPL_oc6yuICACFojEAAQARgAGAEYAiITbGVzIGZyaW5nYWxlcyBsYXZhbDICZnKSARRicmVha2Zhc3RfcmVzdGF1cmFudKoBNRABGh4QASIasU6ni1Oc0k-e-ecmICVLJ4TRK76HszS1FrgqESINbGVzIGZyaW5nYWxlcygE,y,T7NFWvuH8XI;mv:[[45.620182199999995,-73.65968649999999],[45.530364299999995,-73.8163678]];tbs:lrf:!1m4!1u3!2m2!3m1!1e1!1m4!1u2!2m2!2m1!1e1!1m4!1u1!2m2!1m1!1e1!1m4!1u1!2m2!1m1!1e2!2m1!1e2!2m1!1e1!2m1!1e3!3sIAE,lf:1,lf_ui:9"]}]}},"_links":{"self":[{"href":"https:\/\/lesfringales.com\/fr\/wp-json\/wp\/v2\/product_cat\/54","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lesfringales.com\/fr\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/lesfringales.com\/fr\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/lesfringales.com\/fr\/wp-json\/wp\/v2\/product?product_cat=54"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}